{"id":2941,"date":"2023-12-22T14:21:30","date_gmt":"2023-12-22T17:21:30","guid":{"rendered":"https:\/\/esteticaema.com\/site\/?post_type=product&#038;p=2941"},"modified":"2025-02-18T09:30:50","modified_gmt":"2025-02-18T12:30:50","slug":"crema-de-dia-facial-x-60ml-quimeral-skin","status":"publish","type":"product","link":"https:\/\/esteticaema.com\/site\/producto\/crema-de-dia-facial-x-60ml-quimeral-skin\/","title":{"rendered":"Crema de dia facial x 60ml &#8211; QUIMERAL SKIN"},"content":{"rendered":"<p>La crema facial de dia Phyton-Detox detoxifica la piel de los efectos de la polucion y la protege dela luz azul. <\/p>\n<p>Elimina los excesos de grasitud, regulando el sebo. Hidrata de forma prolongada y protege la piel del estress oxidativo. Aporta amino\u00e1cidos de origen natural. Refuerza la barrera hidrolipidica de la piel, dejando efecto filmogeno no oclusivo. Ademas reproduce el factor hidratante de la piel. <\/p>\n<p>Indicaciones: <\/p>\n<p>Todo tipo de piel: sensibles, grasas , normales, maduras. <\/p>\n<p>De uso: diario<\/p>\n<p>Presentaci\u00f3n: 60 ml<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La crema facial de dia Phyton-Detox detoxifica la piel de los efectos de la polucion y la protege dela luz azul. Elimina los excesos de grasitud, regulando el sebo. Hidrata de forma prolongada y protege la piel del estress oxidativo. Aporta amino\u00e1cidos de origen natural. Refuerza la barrera hidrolipidica de la piel, dejando efecto filmogeno [&hellip;]<\/p>\n","protected":false},"featured_media":2945,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_cat":[82],"product_tag":[],"class_list":{"0":"post-2941","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-faciales","8":"first","9":"instock","10":"shipping-taxable","11":"purchasable","12":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/esteticaema.com\/site\/wp-json\/wp\/v2\/product\/2941"}],"collection":[{"href":"https:\/\/esteticaema.com\/site\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/esteticaema.com\/site\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/esteticaema.com\/site\/wp-json\/wp\/v2\/comments?post=2941"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/esteticaema.com\/site\/wp-json\/wp\/v2\/media\/2945"}],"wp:attachment":[{"href":"https:\/\/esteticaema.com\/site\/wp-json\/wp\/v2\/media?parent=2941"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/esteticaema.com\/site\/wp-json\/wp\/v2\/product_cat?post=2941"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/esteticaema.com\/site\/wp-json\/wp\/v2\/product_tag?post=2941"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}